{"id":2139,"date":"2025-08-29T15:05:52","date_gmt":"2025-08-29T13:05:52","guid":{"rendered":"https:\/\/pininordpol.pl\/delivery-price-list\/"},"modified":"2025-09-05T13:00:07","modified_gmt":"2025-09-05T11:00:07","slug":"delivery-price-list","status":"publish","type":"page","link":"https:\/\/pininordpol.pl\/en\/delivery-price-list\/","title":{"rendered":"Delivery price list"},"content":{"rendered":"<style>.kb-row-layout-id2139_de5a26-53 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id2139_de5a26-53 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id2139_de5a26-53 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:1280px;margin-left:auto;margin-right:auto;padding-top:181px;padding-bottom:220px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id2139_de5a26-53{background-image:url('https:\/\/pininordpol.pl\/wp-content\/uploads\/2025\/09\/dostawa.webp');background-size:cover;background-position:57.99999999999999% 56.99999999999999%;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id2139_de5a26-53 > .kt-row-layout-overlay{opacity:0.00;background:linear-gradient(135deg,rgb(0,0,0) 37%,var(--global-palette2) 99%);}.kb-row-layout-id2139_de5a26-53 .kt-row-layout-bottom-sep{height:100px;}.kb-row-layout-id2139_de5a26-53 .kt-row-layout-bottom-sep svg{width:100%;}.kb-row-layout-id2139_de5a26-53 .kt-row-layout-bottom-sep svg{fill:#ffffff!important;}@media all and (max-width: 1024px){.kb-row-layout-id2139_de5a26-53 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 1024px){.kb-row-layout-id2139_de5a26-53 .kt-row-layout-bottom-sep{height:px;}}@media all and (max-width: 1024px){.kb-row-layout-id2139_de5a26-53 .kt-row-layout-bottom-sep svg{width:%;}}@media all and (max-width: 767px){.kb-row-layout-id2139_de5a26-53 > .kt-row-column-wrap{padding-top:140px;padding-right:10px;padding-bottom:140px;padding-left:10px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id2139_de5a26-53 .kt-row-layout-bottom-sep{height:px;}.kb-row-layout-id2139_de5a26-53 .kt-row-layout-bottom-sep svg{width:%;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id2139_de5a26-53 alignnone kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-gradient\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column2139_65f4aa-6a > .kt-inside-inner-col,.kadence-column2139_65f4aa-6a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2139_65f4aa-6a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2139_65f4aa-6a > .kt-inside-inner-col{flex-direction:column;}.kadence-column2139_65f4aa-6a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2139_65f4aa-6a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2139_65f4aa-6a{position:relative;}@media all and (max-width: 1024px){.kadence-column2139_65f4aa-6a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2139_65f4aa-6a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media (max-width: 768px) {n  .kadence-column2139_65f4aa-6a p {n    display: none;n  }n}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2139_65f4aa-6a\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading2139_fdabe5-3f, .wp-block-kadence-advancedheading.kt-adv-heading2139_fdabe5-3f[data-kb-block=\"kb-adv-heading2139_fdabe5-3f\"]{max-width:550px;margin-bottom:20px;text-align:left;line-height:66px;font-style:normal;text-shadow:2px 1px 1px #1a202c;}.wp-block-kadence-advancedheading.kt-adv-heading2139_fdabe5-3f mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading2139_fdabe5-3f[data-kb-block=\"kb-adv-heading2139_fdabe5-3f\"] mark.kt-highlight{font-style:normal;background-image:linear-gradient(135deg,var(u002du002dglobal-palette2) 3%,rgb(251,147,37) 100%);-webkit-background-clip:text;background-clip:text;-webkit-text-fill-color:transparent;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading2139_fdabe5-3f img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading2139_fdabe5-3f[data-kb-block=\"kb-adv-heading2139_fdabe5-3f\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading2139_fdabe5-3f, .wp-block-kadence-advancedheading.kt-adv-heading2139_fdabe5-3f[data-kb-block=\"kb-adv-heading2139_fdabe5-3f\"]{text-shadow:2px 1px 1px #1a202c;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading2139_fdabe5-3f, .wp-block-kadence-advancedheading.kt-adv-heading2139_fdabe5-3f[data-kb-block=\"kb-adv-heading2139_fdabe5-3f\"]{text-shadow:2px 1px 1px #1a202c;font-size:42px;}}<\/style>\n<h1 class=\"kt-adv-heading2139_fdabe5-3f wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading2139_fdabe5-3f\">DELIVERY PRICE<\/h1>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id2139_2dbac1-a1 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id2139_2dbac1-a1 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id2139_2dbac1-a1 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:80px;padding-bottom:80px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id2139_2dbac1-a1 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id2139_2dbac1-a1 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id2139_2dbac1-a1 > .kt-row-column-wrap{padding-right:10px;padding-left:10px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id2139_2dbac1-a1 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column2139_28cd68-e0 > .kt-inside-inner-col,.kadence-column2139_28cd68-e0 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2139_28cd68-e0 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2139_28cd68-e0 > .kt-inside-inner-col{flex-direction:column;}.kadence-column2139_28cd68-e0 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2139_28cd68-e0 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2139_28cd68-e0{position:relative;}@media all and (max-width: 1024px){.kadence-column2139_28cd68-e0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2139_28cd68-e0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2139_28cd68-e0\"><div class=\"kt-inside-inner-col\">\n<p>We make sure that shopping in the Pini NordPol store is comfortable at every stage \u2013 also during delivery. We offer various methods of transport to ensure that your ordered products reach you quickly, safely and comfortably. Whether you choose courier delivery, parcel locker or personal collection, we make sure that your order arrives in perfect condition and on time.  <\/p>\n\n\n\n<p>Due to the size of our products, delivery prices may vary; the more items you order, the more the shipping price may change. The fee will be visible when you place your order.<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id2139_da99be-f2 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id2139_da99be-f2 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id2139_da99be-f2 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr) minmax(0, 2fr);}.kb-row-layout-id2139_da99be-f2 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id2139_da99be-f2 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr) minmax(0, 2fr);}}@media all and (max-width: 767px){.kb-row-layout-id2139_da99be-f2 > .kt-row-column-wrap{padding-right:10px;padding-left:10px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id2139_da99be-f2 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-right-golden kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column2139_2e83a1-fa > .kt-inside-inner-col,.kadence-column2139_2e83a1-fa > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2139_2e83a1-fa > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2139_2e83a1-fa > .kt-inside-inner-col{flex-direction:column;}.kadence-column2139_2e83a1-fa > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2139_2e83a1-fa > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2139_2e83a1-fa{position:relative;}@media all and (max-width: 1024px){.kadence-column2139_2e83a1-fa > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2139_2e83a1-fa > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2139_2e83a1-fa\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading2139_63e132-c9, .wp-block-kadence-advancedheading.kt-adv-heading2139_63e132-c9[data-kb-block=\"kb-adv-heading2139_63e132-c9\"]{font-size:26px;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading2139_63e132-c9 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading2139_63e132-c9[data-kb-block=\"kb-adv-heading2139_63e132-c9\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading2139_63e132-c9 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading2139_63e132-c9[data-kb-block=\"kb-adv-heading2139_63e132-c9\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading2139_63e132-c9 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading2139_63e132-c9\">Personal collection<\/h2>\n<\/div><\/div>\n\n\n<style>.kadence-column2139_998790-89 > .kt-inside-inner-col,.kadence-column2139_998790-89 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2139_998790-89 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2139_998790-89 > .kt-inside-inner-col{flex-direction:column;}.kadence-column2139_998790-89 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2139_998790-89 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2139_998790-89{position:relative;}@media all and (max-width: 1024px){.kadence-column2139_998790-89 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2139_998790-89 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2139_998790-89\"><div class=\"kt-inside-inner-col\">\n<p>Nordpol Sp. z o.o.<\/p>\n\n\n\n<p>Wiejska 2a<\/p>\n\n\n\n<p>87-704 B\u0105dkowo (Kuyavian-Pomeranian Voivodeship)<\/p>\n\n\n\n<p>Phone: <a href=\"http:\/\/+48572435279\">+48 572 435 279<\/a><\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id2139_4ad145-a1 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id2139_4ad145-a1 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id2139_4ad145-a1 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:80px;padding-bottom:24px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id2139_4ad145-a1 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id2139_4ad145-a1 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id2139_4ad145-a1 > .kt-row-column-wrap{padding-right:10px;padding-left:10px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id2139_4ad145-a1 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column2139_49f7f0-b1 > .kt-inside-inner-col,.kadence-column2139_49f7f0-b1 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2139_49f7f0-b1 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2139_49f7f0-b1 > .kt-inside-inner-col{flex-direction:column;}.kadence-column2139_49f7f0-b1 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2139_49f7f0-b1 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2139_49f7f0-b1{position:relative;}@media all and (max-width: 1024px){.kadence-column2139_49f7f0-b1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2139_49f7f0-b1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2139_49f7f0-b1\"><div class=\"kt-inside-inner-col\">\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:24% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"600\" src=\"https:\/\/pininordpol.pl\/wp-content\/uploads\/2025\/09\/InPost_logo_2024.png\" alt=\"\" class=\"wp-image-1471 size-full\" srcset=\"https:\/\/pininordpol.pl\/wp-content\/uploads\/2025\/09\/InPost_logo_2024.png 1000w, https:\/\/pininordpol.pl\/wp-content\/uploads\/2025\/09\/InPost_logo_2024-300x180.png 300w, https:\/\/pininordpol.pl\/wp-content\/uploads\/2025\/09\/InPost_logo_2024-768x461.png 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>Parcel locker<br>Parcel locker size B \u2013 PLN 12.99<br>Parcel locker size C \u2013 PLN 14.99<\/p>\n\n\n\n<p>Courier delivery up to 5 kg PLN 13.99<\/p>\n\n\n\n<p>Courier delivery over 5 kg to 10 kg PLN 15.99<\/p>\n\n\n\n<p>Courier delivery over 10 kg to 15 kg PLN 16.99<\/p>\n\n\n\n<p>Courier delivery over 15 kg to 20 kg PLN 17.99<\/p>\n\n\n\n<p>Courier delivery over 20 kg to 25 kg PLN 18.99<\/p>\n\n\n\n<p>Courier delivery over 25 kg to 30 kg PLN 19.99<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:24% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"404\" height=\"404\" src=\"https:\/\/pininordpol.pl\/wp-content\/uploads\/2025\/09\/FORMA_ZNAKU_POZYTYW.png\" alt=\"\" class=\"wp-image-1472 size-full\" srcset=\"https:\/\/pininordpol.pl\/wp-content\/uploads\/2025\/09\/FORMA_ZNAKU_POZYTYW.png 404w, https:\/\/pininordpol.pl\/wp-content\/uploads\/2025\/09\/FORMA_ZNAKU_POZYTYW-300x300.png 300w, https:\/\/pininordpol.pl\/wp-content\/uploads\/2025\/09\/FORMA_ZNAKU_POZYTYW-150x150.png 150w, https:\/\/pininordpol.pl\/wp-content\/uploads\/2025\/09\/FORMA_ZNAKU_POZYTYW-100x100.png 100w\" sizes=\"auto, (max-width: 404px) 100vw, 404px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>Parcel machine<\/p>\n\n\n\n<p>Size M \u2013 PLN 9<\/p>\n\n\n\n<p>Size L \u2013 PLN 10.50<\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>DELIVERY PRICE We make sure that shopping in the Pini NordPol store is comfortable at every stage \u2013 also during delivery. We offer various methods of transport to ensure that your ordered products reach you quickly, safely and comfortably. Whether you choose courier delivery, parcel locker or personal collection, we make sure that your order&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"disable","_kad_post_title":"hide","_kad_post_layout":"fullwidth","_kad_post_sidebar_id":"","_kad_post_content_style":"unboxed","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-2139","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Delivery price list - Pini NordPol<\/title>\n<meta name=\"description\" content=\"Delivery pricing: check the shipping costs and options for our products. Fast delivery and safe delivery to the indicated address.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Delivery price list - Pini NordPol\" \/>\n<meta property=\"og:description\" content=\"Delivery pricing: check the shipping costs and options for our products. Fast delivery and safe delivery to the indicated address.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pininordpol.pl\/en\/delivery-price-list\/\" \/>\n<meta property=\"og:site_name\" content=\"Pini NordPol\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pininordpol\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-05T11:00:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pininordpol.pl\/wp-content\/uploads\/2025\/09\/InPost_logo_2024.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pininordpol.pl\\\/en\\\/delivery-price-list\\\/\",\"url\":\"https:\\\/\\\/pininordpol.pl\\\/en\\\/delivery-price-list\\\/\",\"name\":\"Delivery price list - Pini NordPol\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pininordpol.pl\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pininordpol.pl\\\/en\\\/delivery-price-list\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pininordpol.pl\\\/en\\\/delivery-price-list\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pininordpol.pl\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/InPost_logo_2024.png\",\"datePublished\":\"2025-08-29T13:05:52+00:00\",\"dateModified\":\"2025-09-05T11:00:07+00:00\",\"description\":\"Delivery pricing: check the shipping costs and options for our products. Fast delivery and safe delivery to the indicated address.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pininordpol.pl\\\/en\\\/delivery-price-list\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pininordpol.pl\\\/en\\\/delivery-price-list\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/pininordpol.pl\\\/en\\\/delivery-price-list\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pininordpol.pl\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/InPost_logo_2024.png\",\"contentUrl\":\"https:\\\/\\\/pininordpol.pl\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/InPost_logo_2024.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pininordpol.pl\\\/en\\\/delivery-price-list\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Homepage\",\"item\":\"https:\\\/\\\/pininordpol.pl\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Delivery price list\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pininordpol.pl\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/pininordpol.pl\\\/en\\\/\",\"name\":\"Pini NordPol\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/pininordpol.pl\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pininordpol.pl\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pininordpol.pl\\\/en\\\/#organization\",\"name\":\"Pini NordPol\",\"url\":\"https:\\\/\\\/pininordpol.pl\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/pininordpol.pl\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pininordpol.pl\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/cropped-nordbol_logo_blue.png\",\"contentUrl\":\"https:\\\/\\\/pininordpol.pl\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/cropped-nordbol_logo_blue.png\",\"width\":460,\"height\":184,\"caption\":\"Pini NordPol\"},\"image\":{\"@id\":\"https:\\\/\\\/pininordpol.pl\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pininordpol\",\"https:\\\/\\\/www.tiktok.com\\\/@pini.nordpol\",\"https:\\\/\\\/www.instagram.com\\\/pini.nordpol\",\"https:\\\/\\\/www.youtube.com\\\/@PiniNordpol\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Delivery price list - Pini NordPol","description":"Delivery pricing: check the shipping costs and options for our products. Fast delivery and safe delivery to the indicated address.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"en_US","og_type":"article","og_title":"Delivery price list - Pini NordPol","og_description":"Delivery pricing: check the shipping costs and options for our products. Fast delivery and safe delivery to the indicated address.","og_url":"https:\/\/pininordpol.pl\/en\/delivery-price-list\/","og_site_name":"Pini NordPol","article_publisher":"https:\/\/www.facebook.com\/pininordpol","article_modified_time":"2025-09-05T11:00:07+00:00","og_image":[{"width":1000,"height":600,"url":"https:\/\/pininordpol.pl\/wp-content\/uploads\/2025\/09\/InPost_logo_2024.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pininordpol.pl\/en\/delivery-price-list\/","url":"https:\/\/pininordpol.pl\/en\/delivery-price-list\/","name":"Delivery price list - Pini NordPol","isPartOf":{"@id":"https:\/\/pininordpol.pl\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pininordpol.pl\/en\/delivery-price-list\/#primaryimage"},"image":{"@id":"https:\/\/pininordpol.pl\/en\/delivery-price-list\/#primaryimage"},"thumbnailUrl":"https:\/\/pininordpol.pl\/wp-content\/uploads\/2025\/09\/InPost_logo_2024.png","datePublished":"2025-08-29T13:05:52+00:00","dateModified":"2025-09-05T11:00:07+00:00","description":"Delivery pricing: check the shipping costs and options for our products. Fast delivery and safe delivery to the indicated address.","breadcrumb":{"@id":"https:\/\/pininordpol.pl\/en\/delivery-price-list\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pininordpol.pl\/en\/delivery-price-list\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/pininordpol.pl\/en\/delivery-price-list\/#primaryimage","url":"https:\/\/pininordpol.pl\/wp-content\/uploads\/2025\/09\/InPost_logo_2024.png","contentUrl":"https:\/\/pininordpol.pl\/wp-content\/uploads\/2025\/09\/InPost_logo_2024.png"},{"@type":"BreadcrumbList","@id":"https:\/\/pininordpol.pl\/en\/delivery-price-list\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Homepage","item":"https:\/\/pininordpol.pl\/en\/"},{"@type":"ListItem","position":2,"name":"Delivery price list"}]},{"@type":"WebSite","@id":"https:\/\/pininordpol.pl\/en\/#website","url":"https:\/\/pininordpol.pl\/en\/","name":"Pini NordPol","description":"","publisher":{"@id":"https:\/\/pininordpol.pl\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pininordpol.pl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/pininordpol.pl\/en\/#organization","name":"Pini NordPol","url":"https:\/\/pininordpol.pl\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/pininordpol.pl\/en\/#\/schema\/logo\/image\/","url":"https:\/\/pininordpol.pl\/wp-content\/uploads\/2025\/08\/cropped-nordbol_logo_blue.png","contentUrl":"https:\/\/pininordpol.pl\/wp-content\/uploads\/2025\/08\/cropped-nordbol_logo_blue.png","width":460,"height":184,"caption":"Pini NordPol"},"image":{"@id":"https:\/\/pininordpol.pl\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pininordpol","https:\/\/www.tiktok.com\/@pini.nordpol","https:\/\/www.instagram.com\/pini.nordpol","https:\/\/www.youtube.com\/@PiniNordpol"]}]}},"taxonomy_info":[],"featured_image_src_large":false,"author_info":{"display_name":"dawid","author_link":"https:\/\/pininordpol.pl\/en\/author\/dawid\/"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/pininordpol.pl\/en\/wp-json\/wp\/v2\/pages\/2139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pininordpol.pl\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pininordpol.pl\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pininordpol.pl\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pininordpol.pl\/en\/wp-json\/wp\/v2\/comments?post=2139"}],"version-history":[{"count":8,"href":"https:\/\/pininordpol.pl\/en\/wp-json\/wp\/v2\/pages\/2139\/revisions"}],"predecessor-version":[{"id":2563,"href":"https:\/\/pininordpol.pl\/en\/wp-json\/wp\/v2\/pages\/2139\/revisions\/2563"}],"wp:attachment":[{"href":"https:\/\/pininordpol.pl\/en\/wp-json\/wp\/v2\/media?parent=2139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}